{"id":13772,"date":"2021-12-04T12:51:40","date_gmt":"2021-12-04T11:51:40","guid":{"rendered":"https:\/\/www.strimgroup.com\/?post_type=tribe_events&#038;p=13772"},"modified":"2021-12-04T12:58:56","modified_gmt":"2021-12-04T11:58:56","slug":"bb22-strategieimplementierung-zh","status":"publish","type":"tribe_events","link":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/","title":{"rendered":"Business Breakfast &#8220;Aktuelle Herausforderungen der Strategieimplementierung&#8221;, Z\u00fcrich, Mai 2022"},"content":{"rendered":"<p>Das Business Breakfast &#8220;<strong>Aktuelle Herausforderungen der <a href=\"https:\/\/www.strimgroup.com\/en\/blog\/category\/implementierung\/\" target=\"_blank\" rel=\"noopener\">Strategieimplementierung<\/a><\/strong>&#8221; findet <strong>am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr<\/strong> statt.<\/p>\n<p>F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant an. Mehr und bessere Daten und Informationen haben eine pr\u00e4zise Segmentierung und Ausrichtung von Kunden, Lieferanten und sogar der Belegschaft erm\u00f6glicht.<\/p>\n<p>Ein solches Gesch\u00e4ftsumfeld erfordert effektive Strategien und exzellente Ausf\u00fchrung. Der Fokus liegt dabei<\/p>\n<ul>\n<li>auf der Verbesserung der organisatorischen F\u00e4higkeiten, um bessere Gesch\u00e4ftsergebnisse zu erzielen und Anst\u00f6\u00dfe f\u00fcr Innovation zu geben,<\/li>\n<li>auf der \u00dcberwindung eines kritischen Mangels an Talenten,<\/li>\n<li>auf einem stringenten Kostenmanagement und konsequenter Prozessverbesserung, sowie<\/li>\n<li>auf dem Aufbau starker Organisationskulturen, um die Leistungsf\u00e4higkeit zu steigern.<\/li>\n<\/ul>\n<p>Das Motto der STRIM Unternehmensgruppe hierzu lautet &#8220;<a href=\"https:\/\/www.strimgroup.com\/blog\/strategieimplementierung-klare-linie\/\" target=\"_blank\" rel=\"noopener noreferrer\">Strategieumsetzung mit klarer Linie<\/a>&#8220;.<\/p>\n<p>Folgende <strong><span style=\"color: #333399;\">Agenda<\/span> <\/strong>erwartet Sie:<\/p>\n<ul>\n<li>Begr\u00fc\u00dfung und kurze Vorstellung<\/li>\n<li>Impulsvortrag und Diskussion 1: Herausforderungen &amp; Erfolgsfaktoren in der Strategieimplementierung<\/li>\n<li>Pause mit Fr\u00fchst\u00fcck<\/li>\n<li>Impulsvortrag und Diskussion 2: Praxisbeispiel zur Strategieimplementierung<\/li>\n<li>Austausch mit Fr\u00fchst\u00fcck<\/li>\n<li>Verabschiedung<\/li>\n<\/ul>\n<p>Welchen <strong><span style=\"color: #333399;\">Nutzen<\/span> <\/strong>d\u00fcrfen Sie erwarten?<\/p>\n<ul>\n<li>Sie erhalten konkrete Ansatzpunkte f\u00fcr eine praxistaugliche Umsetzung.<\/li>\n<li>Sie vertiefen ihr Wissen hinsichtlich fundierter Strategieans\u00e4tze.<\/li>\n<li>Sie erhalten Impulse aus interessanten Praxisprojekten<\/li>\n<li>Sie vertiefen Ihr Wissen im Rahmen der Diskussionen und des Erfahrungsaustauschs und gewinnen daraus konkrete Handlungsempfehlungen.<\/li>\n<\/ul>\n<p>Der symbolische und freiwillig zu entrichtende Kostenbeitrag in H\u00f6he von EUR 15,00 wird seitens der Veranstalter gro\u00dfz\u00fcgig aufgerundet und an die <a href=\"https:\/\/www.aufwind-mannheim.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Organisation Aufwind<\/a> gespendet.<\/p>\n<p><strong><span style=\"color: #333399;\">Zielgruppe<\/span><\/strong>:<\/p>\n<ul>\n<li>Gesch\u00e4ftsf\u00fchrer:innen,<\/li>\n<li>Leiter:innen der Organisationsentwicklung<\/li>\n<li>Verantwortliche f\u00fcr Unternehmens- und Teilstrategien<\/li>\n<li>Verantwortliche f\u00fcr Unternehmenskommunikation<\/li>\n<li>Personalleiter:innen<\/li>\n<\/ul>\n<p>Frau Christiane Mayer steht Ihnen f\u00fcr R\u00fcckfragen zur Verf\u00fcgung und nimmt gerne Ihre verbindliche Anmeldung entgegen.<\/p>\n<p><a href=\"https:\/\/www.strimgroup.com\/wp-content\/uploads\/2015\/09\/Christiane-Mayer-2016.png\"><img decoding=\"async\" width=\"250\" height=\"180\" class=\"size-full wp-image-4020 alignleft\" src=\"https:\/\/www.strimgroup.com\/wp-content\/uploads\/2015\/09\/Christiane-Mayer-2016.png\" alt=\"Christiane-Mayer-2016\" \/><\/a>Frau Christiane Mayer<\/p>\n<p>Morgenr\u00f6te 8a, D-68305 Mannheim<br \/>\nTel.: +49 621 7481 742, Fax: +49 621 7481 741<\/p>\n<p>E-Mail: christiane.mayer@strimgroup.org<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"fusion-button-wrapper\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"\/?page_id=3047\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Jetzt anmelden<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Business Breakfast &#8220;Aktuelle Herausforderungen der Strategieimplementierung&#8221; findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":13763,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[634,259,639,592,642,643,6,791,7],"tribe_events_cat":[305],"class_list":["post-13772","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-4dx","tag-leitbild","tag-managementsystem","tag-organisationsentwicklung","tag-scoreboard","tag-st-galler-management-haus","tag-strategieimplementierung","tag-strategieregelkreis","tag-strategieumsetzung","tribe_events_cat-fachtagungen-2","cat_fachtagungen-2"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Das Business Breakfast &quot;Aktuelle Herausforderungen der Strategieimplementierung&quot; findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dr. Volker Mayer\"\/>\n\t<meta name=\"keywords\" content=\"4dx,leitbild,managementsystem,organisationsentwicklung,scoreboard,st. galler management haus,strategieimplementierung,strategieregelkreis,strategieumsetzung\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"STRIMgroup | Mit klarer Linie von der Strategie, \u00fcber deren Umsetzung, bis hin zur Analytik\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Business Breakfast \u201cAktuelle Herausforderungen der Strategieimplementierung\u201d, Z\u00fcrich, Mai 2022 | STRIMgroup\" \/>\n\t\t<meta property=\"og:description\" content=\"Das Business Breakfast &quot;Aktuelle Herausforderungen der Strategieimplementierung&quot; findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-12-04T11:51:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-12-04T11:58:56+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@STRIMgroup\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Business Breakfast \u201cAktuelle Herausforderungen der Strategieimplementierung\u201d, Z\u00fcrich, Mai 2022 | STRIMgroup\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Das Business Breakfast &quot;Aktuelle Herausforderungen der Strategieimplementierung&quot; findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@STRIMgroup\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/events\\\/#listItem\",\"name\":\"Events\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/events\\\/#listItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/events\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/blog\\\/tag\\\/strategieimplementierung\\\/#listItem\",\"name\":\"Strategieimplementierung\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/blog\\\/tag\\\/strategieimplementierung\\\/#listItem\",\"position\":3,\"name\":\"Strategieimplementierung\",\"item\":\"https:\\\/\\\/www.strimgroup.com\\\/blog\\\/tag\\\/strategieimplementierung\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#listItem\",\"name\":\"Business Breakfast &#8220;Aktuelle Herausforderungen der Strategieimplementierung&#8221;, Z\\u00fcrich, Mai 2022\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/events\\\/#listItem\",\"name\":\"Events\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#listItem\",\"position\":4,\"name\":\"Business Breakfast &#8220;Aktuelle Herausforderungen der Strategieimplementierung&#8221;, Z\\u00fcrich, Mai 2022\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/blog\\\/tag\\\/strategieimplementierung\\\/#listItem\",\"name\":\"Strategieimplementierung\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/#organization\",\"name\":\"STRIMgroup\",\"description\":\"Mit klarer Linie von der Strategie, \\u00fcber deren Umsetzung, bis hin zur Analytik\",\"url\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/\",\"telephone\":\"+496217481742\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.strimgroup.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/strimgroup3.jpg\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#organizationLogo\",\"width\":769,\"height\":206},\"image\":{\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/STRIMgroup\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/volker-mayer-466a2940\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/blog\\\/author\\\/vmayer\\\/#author\",\"url\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/blog\\\/author\\\/vmayer\\\/\",\"name\":\"Dr. Volker Mayer\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4ae3d5c8186300b9d7a274e6607b9ad88321f35b712653c2e7452dce4acaff1?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dr. Volker Mayer\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#webpage\",\"url\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/\",\"name\":\"Business Breakfast \\u201cAktuelle Herausforderungen der Strategieimplementierung\\u201d, Z\\u00fcrich, Mai 2022 | STRIMgroup\",\"description\":\"Das Business Breakfast \\\"Aktuelle Herausforderungen der Strategieimplementierung\\\" findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\\u00fchrungskr\\u00e4fte stehen im gegenw\\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\\u00e4rkte und Vertriebssysteme rasant\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/blog\\\/author\\\/vmayer\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/blog\\\/author\\\/vmayer\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.strimgroup.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/shutterstock_655319341-klein.jpg\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#mainImage\",\"width\":1152,\"height\":768},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/event\\\/bb22-strategieimplementierung-zh\\\/#mainImage\"},\"datePublished\":\"2021-12-04T12:51:40+01:00\",\"dateModified\":\"2021-12-04T12:58:56+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/\",\"name\":\"STRIMgroup\",\"description\":\"Mit klarer Linie von der Strategie, \\u00fcber deren Umsetzung, bis hin zur Analytik\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.strimgroup.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Business Breakfast \u201cAktuelle Herausforderungen der Strategieimplementierung\u201d, Z\u00fcrich, Mai 2022 | STRIMgroup","description":"Das Business Breakfast \"Aktuelle Herausforderungen der Strategieimplementierung\" findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant","canonical_url":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/","robots":"max-image-preview:large","keywords":"4dx,leitbild,managementsystem,organisationsentwicklung,scoreboard,st. galler management haus,strategieimplementierung,strategieregelkreis,strategieumsetzung","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.strimgroup.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/en\/events\/#listItem","name":"Events"}},{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/en\/events\/#listItem","position":2,"name":"Events","item":"https:\/\/www.strimgroup.com\/en\/events\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/blog\/tag\/strategieimplementierung\/#listItem","name":"Strategieimplementierung"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/blog\/tag\/strategieimplementierung\/#listItem","position":3,"name":"Strategieimplementierung","item":"https:\/\/www.strimgroup.com\/blog\/tag\/strategieimplementierung\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#listItem","name":"Business Breakfast &#8220;Aktuelle Herausforderungen der Strategieimplementierung&#8221;, Z\u00fcrich, Mai 2022"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/en\/events\/#listItem","name":"Events"}},{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#listItem","position":4,"name":"Business Breakfast &#8220;Aktuelle Herausforderungen der Strategieimplementierung&#8221;, Z\u00fcrich, Mai 2022","previousItem":{"@type":"ListItem","@id":"https:\/\/www.strimgroup.com\/blog\/tag\/strategieimplementierung\/#listItem","name":"Strategieimplementierung"}}]},{"@type":"Organization","@id":"https:\/\/www.strimgroup.com\/en\/#organization","name":"STRIMgroup","description":"Mit klarer Linie von der Strategie, \u00fcber deren Umsetzung, bis hin zur Analytik","url":"https:\/\/www.strimgroup.com\/en\/","telephone":"+496217481742","logo":{"@type":"ImageObject","url":"https:\/\/www.strimgroup.com\/wp-content\/uploads\/2023\/06\/strimgroup3.jpg","@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#organizationLogo","width":769,"height":206},"image":{"@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/STRIMgroup","https:\/\/www.linkedin.com\/in\/volker-mayer-466a2940\/"]},{"@type":"Person","@id":"https:\/\/www.strimgroup.com\/en\/blog\/author\/vmayer\/#author","url":"https:\/\/www.strimgroup.com\/en\/blog\/author\/vmayer\/","name":"Dr. Volker Mayer","image":{"@type":"ImageObject","@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b4ae3d5c8186300b9d7a274e6607b9ad88321f35b712653c2e7452dce4acaff1?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dr. Volker Mayer"}},{"@type":"WebPage","@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#webpage","url":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/","name":"Business Breakfast \u201cAktuelle Herausforderungen der Strategieimplementierung\u201d, Z\u00fcrich, Mai 2022 | STRIMgroup","description":"Das Business Breakfast \"Aktuelle Herausforderungen der Strategieimplementierung\" findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.strimgroup.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#breadcrumblist"},"author":{"@id":"https:\/\/www.strimgroup.com\/en\/blog\/author\/vmayer\/#author"},"creator":{"@id":"https:\/\/www.strimgroup.com\/en\/blog\/author\/vmayer\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.strimgroup.com\/wp-content\/uploads\/2016\/01\/shutterstock_655319341-klein.jpg","@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#mainImage","width":1152,"height":768},"primaryImageOfPage":{"@id":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/#mainImage"},"datePublished":"2021-12-04T12:51:40+01:00","dateModified":"2021-12-04T12:58:56+01:00"},{"@type":"WebSite","@id":"https:\/\/www.strimgroup.com\/en\/#website","url":"https:\/\/www.strimgroup.com\/en\/","name":"STRIMgroup","description":"Mit klarer Linie von der Strategie, \u00fcber deren Umsetzung, bis hin zur Analytik","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.strimgroup.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"STRIMgroup | Mit klarer Linie von der Strategie, \u00fcber deren Umsetzung, bis hin zur Analytik","og:type":"article","og:title":"Business Breakfast \u201cAktuelle Herausforderungen der Strategieimplementierung\u201d, Z\u00fcrich, Mai 2022 | STRIMgroup","og:description":"Das Business Breakfast &quot;Aktuelle Herausforderungen der Strategieimplementierung&quot; findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant","og:url":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/","article:published_time":"2021-12-04T11:51:40+00:00","article:modified_time":"2021-12-04T11:58:56+00:00","twitter:card":"summary","twitter:site":"@STRIMgroup","twitter:title":"Business Breakfast \u201cAktuelle Herausforderungen der Strategieimplementierung\u201d, Z\u00fcrich, Mai 2022 | STRIMgroup","twitter:description":"Das Business Breakfast &quot;Aktuelle Herausforderungen der Strategieimplementierung&quot; findet am Donnerstag, den 12. Mai 2022, von 8:30 Uhr bis ca. 11 Uhr statt. F\u00fchrungskr\u00e4fte stehen im gegenw\u00e4rtigen Wirtschaftsumfeld vor erheblichen Herausforderungen und Chancen. Die Erwartungen der Kunden an schnellere, bessere und billigere Produkte und Dienstleistungen steigen nicht zuletzt aufgrund der Schaffung globaler M\u00e4rkte und Vertriebssysteme rasant","twitter:creator":"@STRIMgroup"},"aioseo_meta_data":{"post_id":"13772","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"WebPage","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-12-04 11:46:02","updated":"2025-07-05 07:30:20","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.strimgroup.com\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.strimgroup.com\/en\/events\/\" title=\"Events\">Events<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.strimgroup.com\/blog\/tag\/strategieimplementierung\/\" title=\"Strategieimplementierung\">Strategieimplementierung<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBusiness Breakfast \u201cAktuelle Herausforderungen der Strategieimplementierung\u201d, Z\u00fcrich, Mai 2022\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.strimgroup.com\/en\/"},{"label":"Events","link":"https:\/\/www.strimgroup.com\/en\/events\/"},{"label":"Strategieimplementierung","link":"https:\/\/www.strimgroup.com\/blog\/tag\/strategieimplementierung\/"},{"label":"Business Breakfast &#8220;Aktuelle Herausforderungen der Strategieimplementierung&#8221;, Z\u00fcrich, Mai 2022","link":"https:\/\/www.strimgroup.com\/en\/event\/bb22-strategieimplementierung-zh\/"}],"_links":{"self":[{"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/tribe_events\/13772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":4,"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/tribe_events\/13772\/revisions"}],"predecessor-version":[{"id":13781,"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/tribe_events\/13772\/revisions\/13781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/media\/13763"}],"wp:attachment":[{"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/media?parent=13772"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/tags?post=13772"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.strimgroup.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=13772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}